{"id":1808,"date":"2024-03-05T07:02:22","date_gmt":"2024-03-05T07:02:22","guid":{"rendered":"https:\/\/essenled.com\/?post_type=product&#038;p=1808"},"modified":"2024-03-05T07:02:23","modified_gmt":"2024-03-05T07:02:23","slug":"recessed-mounting-led-aluminum-profile","status":"publish","type":"product","link":"https:\/\/essenled.com\/ro\/produs\/recessed-mounting-led-aluminum-profile\/","title":{"rendered":"Montaj \u00eencastrat Profil de aluminiu cu LED-uri"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Profilul de aluminiu cu LED-uri de montare \u00eencastrat\u0103, cu instalare \u00eencorporat\u0103, este potrivit pentru scenele de spa\u021biu de tavan, de sol \u0219i de perete, integrate perfect cu structura cl\u0103dirii.<\/p>\n<p>Profilul LED:  6063-T5, argintiu<\/p>\n<p>Copert\u0103 pentru PC:  Opal, difuzat, transparent<\/p>\n<p>Accesorii:  Clip de montare, suporturi<\/p>\n<p>Lungime: 1m \/ buc\u0103\u021bi, 2m \/ buc\u0103\u021bi, 3m \/ buc\u0103\u021bi, alte lungimi pot fi personalizate<\/p>\n<p><span style=\"color: #ff0000;\">NOT\u0102: Disponibil \u00een alb \u0219i negru.<\/span><\/p>","protected":false},"featured_media":1810,"template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[60,73],"product_tag":[711,712,713,715,714],"class_list":{"0":"post-1808","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-led-profile","7":"product_cat-universal-series","8":"product_tag-recessed-aluminum-channels-for-led-lights","9":"product_tag-recessed-aluminum-channels-led-strip","10":"product_tag-recessed-aluminum-mounting-channel","11":"product_tag-recessed-led-strip-aluminium-profiles","12":"product_tag-recessed-mount-aluminum-channel","14":"first","15":"instock","16":"shipping-taxable","17":"product-type-simple","18":"entry","19":"content-bg","20":"loop-entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Recessed Mounting LED Aluminum Profile - ESSENLED<\/title>\n<meta name=\"description\" content=\"Recessed Mounting LED Aluminum Profile, with embedded installation, is suitable for ceiling, ground and wall space scenes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/essenled.com\/ro\/produs\/recessed-mounting-led-aluminum-profile\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recessed Mounting LED Aluminum Profile\" \/>\n<meta property=\"og:description\" content=\"Recessed Mounting LED Aluminum Profile, with embedded installation, is suitable for ceiling, ground and wall space scenes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/essenled.com\/ro\/produs\/recessed-mounting-led-aluminum-profile\/\" \/>\n<meta property=\"og:site_name\" content=\"ESSENLED\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-05T07:02:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/essenled.com\/wp-content\/uploads\/2024\/03\/Recessed-LED-aluminum-profile-ES-0827.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/recessed-mounting-led-aluminum-profile\\\/\",\"url\":\"https:\\\/\\\/essenled.com\\\/product\\\/recessed-mounting-led-aluminum-profile\\\/\",\"name\":\"Recessed Mounting LED Aluminum Profile - ESSENLED\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/recessed-mounting-led-aluminum-profile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/recessed-mounting-led-aluminum-profile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Recessed-LED-aluminum-profile-ES-0827.webp\",\"datePublished\":\"2024-03-05T07:02:22+00:00\",\"dateModified\":\"2024-03-05T07:02:23+00:00\",\"description\":\"Recessed Mounting LED Aluminum Profile, with embedded installation, is suitable for ceiling, ground and wall space scenes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/recessed-mounting-led-aluminum-profile\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/essenled.com\\\/product\\\/recessed-mounting-led-aluminum-profile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/recessed-mounting-led-aluminum-profile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Recessed-LED-aluminum-profile-ES-0827.webp\",\"contentUrl\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Recessed-LED-aluminum-profile-ES-0827.webp\",\"width\":800,\"height\":800,\"caption\":\"Recessed LED aluminum profile ES-0827\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/recessed-mounting-led-aluminum-profile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/essenled.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Product\",\"item\":\"https:\\\/\\\/essenled.com\\\/fr\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recessed Mounting LED Aluminum Profile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#website\",\"url\":\"https:\\\/\\\/essenled.com\\\/\",\"name\":\"ESSENLED\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/essenled.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#organization\",\"name\":\"ESSENLED\",\"url\":\"https:\\\/\\\/essenled.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Essen-logo.png\",\"contentUrl\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Essen-logo.png\",\"width\":800,\"height\":110,\"caption\":\"ESSENLED\"},\"image\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Montaj \u00eencastrat Profil de aluminiu cu LED-uri - ESSENLED","description":"Profil de aluminiu cu LED-uri de montare \u00eencastrat\u0103, cu instalare \u00eencorporat\u0103, este potrivit pentru scenele de spa\u021biu de tavan, sol \u0219i perete.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/essenled.com\/ro\/produs\/recessed-mounting-led-aluminum-profile\/","og_locale":"ro_RO","og_type":"article","og_title":"Recessed Mounting LED Aluminum Profile","og_description":"Recessed Mounting LED Aluminum Profile, with embedded installation, is suitable for ceiling, ground and wall space scenes.","og_url":"https:\/\/essenled.com\/ro\/produs\/recessed-mounting-led-aluminum-profile\/","og_site_name":"ESSENLED","article_modified_time":"2024-03-05T07:02:23+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/03\/Recessed-LED-aluminum-profile-ES-0827.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Timp estimat pentru citire":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/essenled.com\/product\/recessed-mounting-led-aluminum-profile\/","url":"https:\/\/essenled.com\/product\/recessed-mounting-led-aluminum-profile\/","name":"Montaj \u00eencastrat Profil de aluminiu cu LED-uri - ESSENLED","isPartOf":{"@id":"https:\/\/essenled.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/essenled.com\/product\/recessed-mounting-led-aluminum-profile\/#primaryimage"},"image":{"@id":"https:\/\/essenled.com\/product\/recessed-mounting-led-aluminum-profile\/#primaryimage"},"thumbnailUrl":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/03\/Recessed-LED-aluminum-profile-ES-0827.webp","datePublished":"2024-03-05T07:02:22+00:00","dateModified":"2024-03-05T07:02:23+00:00","description":"Profil de aluminiu cu LED-uri de montare \u00eencastrat\u0103, cu instalare \u00eencorporat\u0103, este potrivit pentru scenele de spa\u021biu de tavan, sol \u0219i perete.","breadcrumb":{"@id":"https:\/\/essenled.com\/product\/recessed-mounting-led-aluminum-profile\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/essenled.com\/product\/recessed-mounting-led-aluminum-profile\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/essenled.com\/product\/recessed-mounting-led-aluminum-profile\/#primaryimage","url":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/03\/Recessed-LED-aluminum-profile-ES-0827.webp","contentUrl":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/03\/Recessed-LED-aluminum-profile-ES-0827.webp","width":800,"height":800,"caption":"Recessed LED aluminum profile ES-0827"},{"@type":"BreadcrumbList","@id":"https:\/\/essenled.com\/product\/recessed-mounting-led-aluminum-profile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/essenled.com\/"},{"@type":"ListItem","position":2,"name":"Product","item":"https:\/\/essenled.com\/fr\/product\/"},{"@type":"ListItem","position":3,"name":"Recessed Mounting LED Aluminum Profile"}]},{"@type":"WebSite","@id":"https:\/\/essenled.com\/#website","url":"https:\/\/essenled.com\/","name":"ESSENLED","description":"","publisher":{"@id":"https:\/\/essenled.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/essenled.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/essenled.com\/#organization","name":"ESSENLED","url":"https:\/\/essenled.com\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/essenled.com\/#\/schema\/logo\/image\/","url":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/01\/Essen-logo.png","contentUrl":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/01\/Essen-logo.png","width":800,"height":110,"caption":"ESSENLED"},"image":{"@id":"https:\/\/essenled.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/essenled.com\/ro\/wp-json\/wp\/v2\/product\/1808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/essenled.com\/ro\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/essenled.com\/ro\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/essenled.com\/ro\/wp-json\/wp\/v2\/product\/1808\/revisions"}],"predecessor-version":[{"id":1816,"href":"https:\/\/essenled.com\/ro\/wp-json\/wp\/v2\/product\/1808\/revisions\/1816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/essenled.com\/ro\/wp-json\/wp\/v2\/media\/1810"}],"wp:attachment":[{"href":"https:\/\/essenled.com\/ro\/wp-json\/wp\/v2\/media?parent=1808"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/essenled.com\/ro\/wp-json\/wp\/v2\/product_brand?post=1808"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/essenled.com\/ro\/wp-json\/wp\/v2\/product_cat?post=1808"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/essenled.com\/ro\/wp-json\/wp\/v2\/product_tag?post=1808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}