{"id":30,"count":3,"description":"","link":"https:\/\/essenled.com\/pt\/categoria-produto\/led-strip\/tunable-white-series\/","name":"S\u00e9rie branca sintoniz\u00e1vel","slug":"tunable-white-series","taxonomy":"product_cat","parent":29,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tunable White Series Archives - ESSENLED<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/essenled.com\/pt\/categoria-produto\/led-strip\/tunable-white-series\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tunable White Series Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/essenled.com\/pt\/categoria-produto\/led-strip\/tunable-white-series\/\" \/>\n<meta property=\"og:site_name\" content=\"ESSENLED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/essenled.com\\\/product-category\\\/led-strip\\\/tunable-white-series\\\/\",\"url\":\"https:\\\/\\\/essenled.com\\\/product-category\\\/led-strip\\\/tunable-white-series\\\/\",\"name\":\"Tunable White Series Archives - ESSENLED\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/product-category\\\/led-strip\\\/tunable-white-series\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/essenled.com\\\/product-category\\\/led-strip\\\/tunable-white-series\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/essenled.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LED Strip\",\"item\":\"https:\\\/\\\/essenled.com\\\/product-category\\\/led-strip\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tunable White Series\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#website\",\"url\":\"https:\\\/\\\/essenled.com\\\/\",\"name\":\"ESSENLED\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/essenled.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#organization\",\"name\":\"ESSENLED\",\"url\":\"https:\\\/\\\/essenled.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Essen-logo.png\",\"contentUrl\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Essen-logo.png\",\"width\":800,\"height\":110,\"caption\":\"ESSENLED\"},\"image\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arquivos da s\u00e9rie Tunable White - ESSENLED","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/essenled.com\/pt\/categoria-produto\/led-strip\/tunable-white-series\/","og_locale":"pt_PT","og_type":"article","og_title":"Tunable White Series Archives","og_url":"https:\/\/essenled.com\/pt\/categoria-produto\/led-strip\/tunable-white-series\/","og_site_name":"ESSENLED","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/essenled.com\/product-category\/led-strip\/tunable-white-series\/","url":"https:\/\/essenled.com\/product-category\/led-strip\/tunable-white-series\/","name":"Arquivos da s\u00e9rie Tunable White - ESSENLED","isPartOf":{"@id":"https:\/\/essenled.com\/#website"},"breadcrumb":{"@id":"https:\/\/essenled.com\/product-category\/led-strip\/tunable-white-series\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/essenled.com\/product-category\/led-strip\/tunable-white-series\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/essenled.com\/"},{"@type":"ListItem","position":2,"name":"LED Strip","item":"https:\/\/essenled.com\/product-category\/led-strip\/"},{"@type":"ListItem","position":3,"name":"Tunable White Series"}]},{"@type":"WebSite","@id":"https:\/\/essenled.com\/#website","url":"https:\/\/essenled.com\/","name":"ESSENLED","description":"","publisher":{"@id":"https:\/\/essenled.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/essenled.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/essenled.com\/#organization","name":"ESSENLED","url":"https:\/\/essenled.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/essenled.com\/#\/schema\/logo\/image\/","url":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/01\/Essen-logo.png","contentUrl":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/01\/Essen-logo.png","width":800,"height":110,"caption":"ESSENLED"},"image":{"@id":"https:\/\/essenled.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/essenled.com\/pt\/wp-json\/wp\/v2\/product_cat\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/essenled.com\/pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/essenled.com\/pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/essenled.com\/pt\/wp-json\/wp\/v2\/product_cat\/29"}],"wp:post_type":[{"href":"https:\/\/essenled.com\/pt\/wp-json\/wp\/v2\/product?product_cat=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}