{"id":73,"count":4,"description":"","link":"https:\/\/essenled.com\/it\/categoria-prodotto\/led-profile\/universal-series\/","name":"Serie universale","slug":"universal-series","taxonomy":"product_cat","parent":60,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Universal Series - ESSENLED<\/title>\n<meta name=\"description\" content=\"The LED aluminum profile Universal series is great for any lighting solution, ultra-narrow models and special conner LED profile models.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/essenled.com\/it\/categoria-prodotto\/led-profile\/universal-series\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Universal Series Archives\" \/>\n<meta property=\"og:description\" content=\"The LED aluminum profile Universal series is great for any lighting solution, ultra-narrow models and special conner LED profile models.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/essenled.com\/it\/categoria-prodotto\/led-profile\/universal-series\/\" \/>\n<meta property=\"og:site_name\" content=\"ESSENLED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/essenled.com\\\/product-category\\\/led-profile\\\/universal-series\\\/\",\"url\":\"https:\\\/\\\/essenled.com\\\/product-category\\\/led-profile\\\/universal-series\\\/\",\"name\":\"Universal Series - ESSENLED\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#website\"},\"description\":\"The LED aluminum profile Universal series is great for any lighting solution, ultra-narrow models and special conner LED profile models.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/product-category\\\/led-profile\\\/universal-series\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/essenled.com\\\/product-category\\\/led-profile\\\/universal-series\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/essenled.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LED Profile\",\"item\":\"https:\\\/\\\/essenled.com\\\/product-category\\\/led-profile\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Universal Series\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#website\",\"url\":\"https:\\\/\\\/essenled.com\\\/\",\"name\":\"ESSENLED\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/essenled.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#organization\",\"name\":\"ESSENLED\",\"url\":\"https:\\\/\\\/essenled.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Essen-logo.png\",\"contentUrl\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Essen-logo.png\",\"width\":800,\"height\":110,\"caption\":\"ESSENLED\"},\"image\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Serie universale - ESSENLED","description":"La serie Universal con profilo in alluminio a LED \u00e8 ideale per qualsiasi soluzione illuminotecnica, per i modelli ultra stretti e per i modelli speciali con profilo a LED conner.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/essenled.com\/it\/categoria-prodotto\/led-profile\/universal-series\/","og_locale":"it_IT","og_type":"article","og_title":"Universal Series Archives","og_description":"The LED aluminum profile Universal series is great for any lighting solution, ultra-narrow models and special conner LED profile models.","og_url":"https:\/\/essenled.com\/it\/categoria-prodotto\/led-profile\/universal-series\/","og_site_name":"ESSENLED","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/essenled.com\/product-category\/led-profile\/universal-series\/","url":"https:\/\/essenled.com\/product-category\/led-profile\/universal-series\/","name":"Serie universale - ESSENLED","isPartOf":{"@id":"https:\/\/essenled.com\/#website"},"description":"La serie Universal con profilo in alluminio a LED \u00e8 ideale per qualsiasi soluzione illuminotecnica, per i modelli ultra stretti e per i modelli speciali con profilo a LED conner.","breadcrumb":{"@id":"https:\/\/essenled.com\/product-category\/led-profile\/universal-series\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/essenled.com\/product-category\/led-profile\/universal-series\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/essenled.com\/"},{"@type":"ListItem","position":2,"name":"LED Profile","item":"https:\/\/essenled.com\/product-category\/led-profile\/"},{"@type":"ListItem","position":3,"name":"Universal Series"}]},{"@type":"WebSite","@id":"https:\/\/essenled.com\/#website","url":"https:\/\/essenled.com\/","name":"ESSENZIALE","description":"","publisher":{"@id":"https:\/\/essenled.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/essenled.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/essenled.com\/#organization","name":"ESSENZIALE","url":"https:\/\/essenled.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/essenled.com\/#\/schema\/logo\/image\/","url":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/01\/Essen-logo.png","contentUrl":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/01\/Essen-logo.png","width":800,"height":110,"caption":"ESSENLED"},"image":{"@id":"https:\/\/essenled.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product_cat\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product_cat\/60"}],"wp:post_type":[{"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product?product_cat=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}