{"id":1636,"date":"2024-03-01T10:43:16","date_gmt":"2024-03-01T10:43:16","guid":{"rendered":"https:\/\/essenled.com\/?post_type=product&#038;p=1636"},"modified":"2024-03-01T10:43:17","modified_gmt":"2024-03-01T10:43:17","slug":"mini-cutting-topside-view-ip67-led-neon-flex","status":"publish","type":"product","link":"https:\/\/essenled.com\/it\/prodotto\/mini-cutting-topside-view-ip67-led-neon-flex\/","title":{"rendered":"Mini taglio 8,33 mm vista dall'alto e dal lato IP67 LED Neon Flex"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Mini taglio 8,33 mm Vista dall'alto e dal lato IP67 LED Neon Flex, il LED Neon Flex pu\u00f2 essere tagliato a intervalli di 8,33 mm per personalizzare la lunghezza della striscia in base a specifici requisiti di installazione, regolazioni e flessibilit\u00e0 nel design.<\/p>\n<p>Vista dall'alto e laterale Il neon flex a LED IP67 ha una lunghezza di taglio di 8,33 mm per taglio. Con le sue dimensioni compatte, il mini neon flex da taglio offre un profilo elegante e sottile, adatto a varie applicazioni di illuminazione per interni ed esterni.<\/p>\n<p>Il neon flessibile a LED da 8,33 mm di Mini Cutting emette luce sia dalla parte superiore che da quella laterale della striscia, offrendo opzioni di illuminazione versatili.<\/p>\n<p>Mini Cutting 8.33mm Top&amp;Side View IP67 LED Neon Flex, la classificazione IP67 garantisce che la striscia sia completamente protetta da polvere e ambienti con elevata umidit\u00e0 o umidit\u00e0.<\/p>","protected":false},"featured_media":1474,"template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[47,39],"product_tag":[661,660,656,658,659,657],"class_list":{"0":"post-1636","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mini-cutting-neon-series","7":"product_cat-neon-strip","8":"product_tag-mini-cut-led-neon-24v-rgbw","9":"product_tag-mini-cut-led-neon-srtip-ip67","10":"product_tag-mini-cutting-neon-flex-ip67","11":"product_tag-mini-cutting-neon-led-strip","12":"product_tag-mini-led-neon-flex-custom-cut","13":"product_tag-ultra-short-cutting-led-neon-flex","15":"first","16":"instock","17":"shipping-taxable","18":"product-type-simple","19":"entry","20":"content-bg","21":"loop-entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mini Cutting 8.33mm Top&amp;Side View IP67 LED Neon Flex - ESSENLED<\/title>\n<meta name=\"description\" content=\"Mini Cutting 8.33mm Top&amp;Side View IP67 LED Neon Flex, can be cut at 8.33mm to customize the length of strip according to specific requirements.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/essenled.com\/it\/prodotto\/mini-cutting-topside-view-ip67-led-neon-flex\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mini Cutting 8.33mm Top&amp;Side View IP67 LED Neon Flex\" \/>\n<meta property=\"og:description\" content=\"Mini Cutting 8.33mm Top&amp;Side View IP67 LED Neon Flex, can be cut at 8.33mm to customize the length of strip according to specific requirements.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/essenled.com\/it\/prodotto\/mini-cutting-topside-view-ip67-led-neon-flex\/\" \/>\n<meta property=\"og:site_name\" content=\"ESSENLED\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-01T10:43:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/essenled.com\/wp-content\/uploads\/2024\/02\/1615-Silicone-LED-Neon-Light-Top-Bend.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/mini-cutting-topside-view-ip67-led-neon-flex\\\/\",\"url\":\"https:\\\/\\\/essenled.com\\\/product\\\/mini-cutting-topside-view-ip67-led-neon-flex\\\/\",\"name\":\"Mini Cutting 8.33mm Top&Side View IP67 LED Neon Flex - ESSENLED\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/mini-cutting-topside-view-ip67-led-neon-flex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/mini-cutting-topside-view-ip67-led-neon-flex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/1615-Silicone-LED-Neon-Light-Top-Bend.webp\",\"datePublished\":\"2024-03-01T10:43:16+00:00\",\"dateModified\":\"2024-03-01T10:43:17+00:00\",\"description\":\"Mini Cutting 8.33mm Top&Side View IP67 LED Neon Flex, can be cut at 8.33mm to customize the length of strip according to specific requirements.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/mini-cutting-topside-view-ip67-led-neon-flex\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/essenled.com\\\/product\\\/mini-cutting-topside-view-ip67-led-neon-flex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/mini-cutting-topside-view-ip67-led-neon-flex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/1615-Silicone-LED-Neon-Light-Top-Bend.webp\",\"contentUrl\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/1615-Silicone-LED-Neon-Light-Top-Bend.webp\",\"width\":800,\"height\":800,\"caption\":\"1615 Silicone LED Neon Light Top Bend\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/essenled.com\\\/product\\\/mini-cutting-topside-view-ip67-led-neon-flex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/essenled.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Product\",\"item\":\"https:\\\/\\\/essenled.com\\\/fr\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mini Cutting 8.33mm Top&#038;Side View IP67 LED Neon Flex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#website\",\"url\":\"https:\\\/\\\/essenled.com\\\/\",\"name\":\"ESSENLED\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/essenled.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#organization\",\"name\":\"ESSENLED\",\"url\":\"https:\\\/\\\/essenled.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Essen-logo.png\",\"contentUrl\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Essen-logo.png\",\"width\":800,\"height\":110,\"caption\":\"ESSENLED\"},\"image\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mini taglio 8,33 mm vista dall'alto e laterale IP67 LED Neon Flex - ESSENLED","description":"Mini taglio 8,33 mm Vista dall'alto e dal lato IP67 LED Neon Flex, pu\u00f2 essere tagliato a 8,33 mm per personalizzare la lunghezza della striscia in base alle esigenze specifiche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/essenled.com\/it\/prodotto\/mini-cutting-topside-view-ip67-led-neon-flex\/","og_locale":"it_IT","og_type":"article","og_title":"Mini Cutting 8.33mm Top&Side View IP67 LED Neon Flex","og_description":"Mini Cutting 8.33mm Top&Side View IP67 LED Neon Flex, can be cut at 8.33mm to customize the length of strip according to specific requirements.","og_url":"https:\/\/essenled.com\/it\/prodotto\/mini-cutting-topside-view-ip67-led-neon-flex\/","og_site_name":"ESSENLED","article_modified_time":"2024-03-01T10:43:17+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/02\/1615-Silicone-LED-Neon-Light-Top-Bend.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/essenled.com\/product\/mini-cutting-topside-view-ip67-led-neon-flex\/","url":"https:\/\/essenled.com\/product\/mini-cutting-topside-view-ip67-led-neon-flex\/","name":"Mini taglio 8,33 mm vista dall'alto e laterale IP67 LED Neon Flex - ESSENLED","isPartOf":{"@id":"https:\/\/essenled.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/essenled.com\/product\/mini-cutting-topside-view-ip67-led-neon-flex\/#primaryimage"},"image":{"@id":"https:\/\/essenled.com\/product\/mini-cutting-topside-view-ip67-led-neon-flex\/#primaryimage"},"thumbnailUrl":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/02\/1615-Silicone-LED-Neon-Light-Top-Bend.webp","datePublished":"2024-03-01T10:43:16+00:00","dateModified":"2024-03-01T10:43:17+00:00","description":"Mini taglio 8,33 mm Vista dall'alto e dal lato IP67 LED Neon Flex, pu\u00f2 essere tagliato a 8,33 mm per personalizzare la lunghezza della striscia in base alle esigenze specifiche.","breadcrumb":{"@id":"https:\/\/essenled.com\/product\/mini-cutting-topside-view-ip67-led-neon-flex\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/essenled.com\/product\/mini-cutting-topside-view-ip67-led-neon-flex\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/essenled.com\/product\/mini-cutting-topside-view-ip67-led-neon-flex\/#primaryimage","url":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/02\/1615-Silicone-LED-Neon-Light-Top-Bend.webp","contentUrl":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/02\/1615-Silicone-LED-Neon-Light-Top-Bend.webp","width":800,"height":800,"caption":"1615 Silicone LED Neon Light Top Bend"},{"@type":"BreadcrumbList","@id":"https:\/\/essenled.com\/product\/mini-cutting-topside-view-ip67-led-neon-flex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/essenled.com\/"},{"@type":"ListItem","position":2,"name":"Product","item":"https:\/\/essenled.com\/fr\/product\/"},{"@type":"ListItem","position":3,"name":"Mini Cutting 8.33mm Top&#038;Side View IP67 LED Neon Flex"}]},{"@type":"WebSite","@id":"https:\/\/essenled.com\/#website","url":"https:\/\/essenled.com\/","name":"ESSENZIALE","description":"","publisher":{"@id":"https:\/\/essenled.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/essenled.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/essenled.com\/#organization","name":"ESSENZIALE","url":"https:\/\/essenled.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/essenled.com\/#\/schema\/logo\/image\/","url":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/01\/Essen-logo.png","contentUrl":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/01\/Essen-logo.png","width":800,"height":110,"caption":"ESSENLED"},"image":{"@id":"https:\/\/essenled.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product\/1636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product\/1636\/revisions"}],"predecessor-version":[{"id":1639,"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product\/1636\/revisions\/1639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/media\/1474"}],"wp:attachment":[{"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/media?parent=1636"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product_brand?post=1636"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product_cat?post=1636"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/essenled.com\/it\/wp-json\/wp\/v2\/product_tag?post=1636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}