{"id":759,"count":1,"description":"","link":"https:\/\/essenled.com\/es\/tag\/80-cri-vs-90-cri\/","name":"80 cri vs 90 cri","slug":"80-cri-vs-90-cri","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>80 cri vs 90 cri Archives - ESSENLED<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/essenled.com\/es\/tag\/80-cri-vs-90-cri\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"80 cri vs 90 cri Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/essenled.com\/es\/tag\/80-cri-vs-90-cri\/\" \/>\n<meta property=\"og:site_name\" content=\"ESSENLED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/essenled.com\\\/tag\\\/80-cri-vs-90-cri\\\/\",\"url\":\"https:\\\/\\\/essenled.com\\\/tag\\\/80-cri-vs-90-cri\\\/\",\"name\":\"80 cri vs 90 cri Archives - ESSENLED\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/tag\\\/80-cri-vs-90-cri\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/essenled.com\\\/tag\\\/80-cri-vs-90-cri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/essenled.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"80 cri vs 90 cri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#website\",\"url\":\"https:\\\/\\\/essenled.com\\\/\",\"name\":\"ESSENLED\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/essenled.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#organization\",\"name\":\"ESSENLED\",\"url\":\"https:\\\/\\\/essenled.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/essenled.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Essen-logo.png\",\"contentUrl\":\"https:\\\/\\\/essenled.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Essen-logo.png\",\"width\":800,\"height\":110,\"caption\":\"ESSENLED\"},\"image\":{\"@id\":\"https:\\\/\\\/essenled.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"80 cri vs 90 cri Archives - ESSENLED","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/essenled.com\/es\/tag\/80-cri-vs-90-cri\/","og_locale":"es_ES","og_type":"article","og_title":"80 cri vs 90 cri Archives","og_url":"https:\/\/essenled.com\/es\/tag\/80-cri-vs-90-cri\/","og_site_name":"ESSENLED","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/essenled.com\/tag\/80-cri-vs-90-cri\/","url":"https:\/\/essenled.com\/tag\/80-cri-vs-90-cri\/","name":"80 cri vs 90 cri Archives - ESSENLED","isPartOf":{"@id":"https:\/\/essenled.com\/#website"},"breadcrumb":{"@id":"https:\/\/essenled.com\/tag\/80-cri-vs-90-cri\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/essenled.com\/tag\/80-cri-vs-90-cri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/essenled.com\/"},{"@type":"ListItem","position":2,"name":"80 cri vs 90 cri"}]},{"@type":"WebSite","@id":"https:\/\/essenled.com\/#website","url":"https:\/\/essenled.com\/","name":"ESSENLED","description":"","publisher":{"@id":"https:\/\/essenled.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/essenled.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/essenled.com\/#organization","name":"ESSENLED","url":"https:\/\/essenled.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/essenled.com\/#\/schema\/logo\/image\/","url":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/01\/Essen-logo.png","contentUrl":"https:\/\/essenled.com\/wp-content\/uploads\/2024\/01\/Essen-logo.png","width":800,"height":110,"caption":"ESSENLED"},"image":{"@id":"https:\/\/essenled.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/essenled.com\/es\/wp-json\/wp\/v2\/tags\/759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/essenled.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/essenled.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/essenled.com\/es\/wp-json\/wp\/v2\/posts?tags=759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}